{"id":2383,"date":"2017-11-07T20:00:50","date_gmt":"2017-11-07T19:00:50","guid":{"rendered":"https:\/\/onload.reinhausen.com\/de\/?p=2383"},"modified":"2023-05-15T13:50:17","modified_gmt":"2023-05-15T11:50:17","slug":"so-bleibt-die-flotte-flott","status":"publish","type":"post","link":"https:\/\/onload.reinhausen.com\/de\/11-2017\/so-bleibt-die-flotte-flott\/","title":{"rendered":"So bleibt die Flotte flott"},"content":{"rendered":"<hr class=\"yellow\">\n<p><span class=\"initial\">\u00dc<\/span>ber die Bade\u00adwan\u00adnen\u00adkurve haben sich Jan Patrick Linos\u00adsier und Rolf Funk schon h\u00e4ufig den Kopf zerbro\u00adchen. Beide sind bei der <a href=\"http:\/\/www.rng.de\/cms\/\" target=\"_blank\" rel=\"noopener\">Rhei\u00adni\u00adschen NETZ\u00adGe\u00adsell\u00adschaft (RNG)<\/a> f\u00fcr das stra\u00adte\u00adgi\u00adsche Asset-Manage\u00adment zust\u00e4ndig und verant\u00adwort\u00adlich f\u00fcr die Zustands- und Risi\u00adko\u00adbe\u00adwer\u00adtung der einge\u00adsetzten&nbsp; Betriebs\u00admittel. Dazu geh\u00f6ren auch die rund 100 Leis\u00adtungs\u00adtrans\u00adfor\u00adma\u00adtoren, die der Verteil\u00adnetz\u00adbe\u00adtreiber aus K\u00f6ln f\u00fcr sein etwa 20.000 Kilo\u00admeter umfas\u00adsendes Strom\u00adnetz betreibt. \u201eWir m\u00fcssen den Zustand unserer Trans\u00adfor\u00adma\u00adtoren sehr genau kennen. Halten sie noch oder m\u00fcssen wir in neue inves\u00adtieren? \u2013 das ist eine Frage, die uns st\u00e4ndig umtreibt. Aber keiner in der Branche wei\u00df genau, wie lange ein Trans\u00adfor\u00admator letzt\u00adend\u00adlich h\u00e4lt\u201c, sagt Linos\u00adsier, der das stra\u00adte\u00adgi\u00adsche Asset-Manage\u00adment leitet.<\/p>\n<h2>MEHR ST\u00d6RUNGEN MIT ZUNEHMENDEM ALTER<\/h2>\n<p>Die Bade\u00adwan\u00adnen\u00adkurve ist ein Modell, um die St\u00f6r\u00adan\u00adf\u00e4l\u00adlig\u00adkeit von Betriebs\u00admit\u00adteln \u00fcber deren gesamte Lebens\u00addauer zu beschreiben: Bei Inbe\u00adtrieb\u00adnahme ist die Ausfall\u00adrate noch sehr hoch. Sind die Start\u00adschwie\u00adrig\u00adkeiten erst einmal besei\u00adtigt, f\u00e4llt die Fehler\u00adquote rasch und pendelt sich auf einem konstant nied\u00adrigen Niveau ein. Daran \u00e4ndert sich lange Zeit nichts. Doch mit zuneh\u00admendem Alter h\u00e4ufen sich die St\u00f6rungen ab einem gewissen Punkt wieder. Tr\u00e4gt man diesen Verlauf in einen Graphen ein, bei dem auf der X\u2011Achse die Zeit und auf der Y\u2011Achse die Ausfall\u00adrate verzeichnet sind, \u00e4hnelt die Kurve dem Quer\u00adschnitt durch eine Bade\u00adwanne.<br>\n<\/p>\n<figure id=\"attachment_2513\" aria-describedby=\"caption-attachment-2513\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2513 size-medium\" src=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Linossier-Babizki-300x200.jpg\" alt width=\"300\" height=\"200\" srcset=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Linossier-Babizki-300x200.jpg 300w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Linossier-Babizki-768x512.jpg 768w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Linossier-Babizki-540x360.jpg 540w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Linossier-Babizki.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><figcaption id=\"caption-attachment-2513\" class=\"wp-caption-text\">Jan Patrick Linos\u00adsier, Leiter des Asset Manage\u00adments bei der RNG (rechts), und Alexei Babizki, Port\u00adfolio Manager bei MR, sind zufrieden mit den Ergeb\u00adnissen der Pilot\u00adstudie. (\u00a9 Dirk Moll)<\/figcaption><\/figure>\n<p>Was Linos\u00adsier und Funk dabei viel Kopf\u00adzer\u00adbre\u00adchen bereitet, ist: An welchem Punkt der Bade\u00adwan\u00adnen\u00adkurve befinden sich ihre Transfor matoren aktuell? Wann beginnt die Ausfall\u00adrate zu steigen? \u201eDann sollten wir n\u00e4mlich eine Erneue\u00adrung einleiten\u201c, sagt Funk, der im stra\u00adte\u00adgi\u00adschen Asset-Manage\u00adment auf die Leis\u00adtungs\u00adtrans\u00adfor\u00adma\u00adtoren spezia\u00adli\u00adsiert ist. Die Frage wird immer akuter: Das Durch\u00adschnitts\u00adalter der Trans\u00adfor\u00adma\u00adtoren bei der RNG betr\u00e4gt 45,7 Jahre. Ein Gro\u00df\u00adteil davon wurde in den 50er- und 60er-Jahren in Betrieb genommen. Die Entschei\u00addung, diese zu erneuern, ist nicht nur eine tech\u00adni\u00adsche, sondern auch eine finan\u00adzi\u00adelle: Ein neuer Leis\u00adtungs\u00adtrans\u00adfor\u00admator dieser Gr\u00f6\u00dfen\u00adord\u00adnung kostet fast eine halbe Million Euro. \u201eFr\u00fcher hat man die Trans\u00adfor\u00adma\u00adtoren einfach nach einer bestimmten Zeit durch neue ersetzt, aber der Kosten\u00addruck ist heute h\u00f6her. Daher wollen wir die Betriebs\u00admittel so lange wie m\u00f6glich optimal ausnutzen\u201c, sagt Linos\u00adsier.<\/p>\n<blockquote><p>\u201eEs gibt Trans\u00adfor\u00adma\u00adtoren im Indus\u00adtrie\u00adbe\u00adreich, die m\u00fcssen schon nach 15 Jahren ersetzt werden, und dann gibt es solche, die nur mit 30 Prozent Last fahren und schon \u00fcber 50 Jahre im Betrieb sind. Das Alter allein sagt also nicht unbe\u00addingt etwas \u00fcber den Zustand aus.\u201c<cite>Alexei Babizki<\/cite><\/p><\/blockquote>\n<p>Mit ihrer alternden Trans\u00adfor\u00adma\u00adto\u00adren\u00adflotte steht die&nbsp; RNG&nbsp; nicht alleine da: In den zwei Jahr\u00adzehnten nach dem&nbsp; Zweiten&nbsp; Welt\u00adkrieg stieg der Bedarf nach immer mehr Strom rasant an. Neue Kraft\u00adwerke wurden gebaut, Leitungen verlegt und zahl\u00adreiche Umspann\u00adwerke errichtet. Das Strom\u00adnetz von heute basiert noch in weiten Teilen auf den Planungen dieser Zeit. Das ist nicht nur in ganz Deutsch\u00adland, sondern in allen modernen Indus\u00adtrie\u00adna\u00adtionen so. Aller\u00addings waren die Last\u00adpro\u00adgnosen damals noch ganz andere.<\/p>\n<p>\u201eDurch die erneu\u00ader\u00adbaren Ener\u00adgien m\u00fcssen Netz\u00adstruk\u00adturen ganz anders gedacht werden, da ist es von stra\u00adte\u00adgi\u00adscher Bedeu\u00adtung, den Zustand unserer Trans\u00adfor\u00adma\u00adtoren genau zu kennen\u201c, betont Linos\u00adsier. Zum einen, weil sich die Auslas\u00adtung der Trans\u00adfor\u00adma\u00adtoren \u00e4ndert, und zum anderen, weil der Netz\u00adumbau manche Anlagen in Zukunft \u00fcber\u00adfl\u00fcssig macht. \u201eWenn wir zu fr\u00fch erneuern, k\u00f6nnte sich das sp\u00e4ter als Fehl\u00adin\u00adves\u00adti\u00adtion heraus\u00adstellen\u201c, erkl\u00e4rt Funk. Eine Bewer\u00adtungs\u00adme\u00adthode, mit der er den Zustand der Trans\u00adfor\u00adma\u00adto\u00adren\u00adflotte genau einsch\u00e4tzen konnte, fehlte bisher.<\/p>\n<h2>KOOPERATION IN DER STRASSENBAHN<\/h2>\n<p>Das sollte sich durch eine zuf\u00e4l\u00adlige Begeg\u00adnung in einer Stra\u00ad\u00dfen\u00adbahn in Lyon \u00e4ndern. Alexei Babizki, Port\u00adfolio Manager bei MR, und Markus Zdrallek, Professor an der Bergi\u00adschen Univer\u00adsit\u00e4t in Wuppertal, kamen dort auf dem Weg zum Flug\u00adhafen zuf\u00e4llig ins Gespr\u00e4ch. Sie hatten gerade den glei\u00adchen Kongress besucht. Zdrallek leitet den <a href=\"https:\/\/www.evt.uni-wuppertal.de\/\" target=\"_blank\" rel=\"noopener\">Lehr\u00adstuhl f\u00fcr Elek\u00adtri\u00adsche Ener\u00adgie\u00adver\u00adsor\u00adgungs\u00adtechnik<\/a> und besch\u00e4f\u00adtigt sich schon seit vielen Jahren mit der Zustands\u00adbe\u00adwer\u00adtung von Betriebs\u00admit\u00adteln in Strom\u00adnetzen. \u201eWir m\u00f6chten den Netz\u00adbe\u00adtrei\u00adbern eine wissen\u00adschaft\u00adliche Basis f\u00fcr intel\u00adli\u00adgente Erneue\u00adrungs\u00adstra\u00adte\u00adgien ihrer Netze bieten\u201c, sagt Zdrallek, \u201eaber die Leis\u00adtungs\u00adtrans\u00adfor\u00adma\u00adtoren fehlten noch in meiner Forschung.\u201c<\/p>\n<div class=\"wpcmsdev-box\">\n<div class=\"box-content\">\n<h5>DIE FLOTTE IMMER IM BLICK \u2013 SO GEHT\u2019S:<\/h5>\n<p>Die Zustands\u00adbe\u00adwer\u00adtung der Trans\u00adfor\u00adma\u00adtoren erfolgt in bis zu drei Schritten, womit die Abschalt\u00adzeit der Trans\u00adfor\u00adma\u00adtoren redu\u00adziert werden kann:<\/p>\n<p><span class=\"numbers\">1<\/span> Im ersten Schritt stellt der Betreiber <strong>bereits bestehende Daten<\/strong> zur Verf\u00fc\u00adgung. Dazu z\u00e4hlen zum Beispiel das Alter der Trans\u00adfor\u00adma\u00adtoren, bereits durch\u00adge\u00adf\u00fchrte Messungen und Infor\u00adma\u00adtionen zur Wartungs\u00adhis\u00adtorie.<\/p>\n<p><span class=\"numbers\">2<\/span> Im zweiten Schritt folgt dann die <strong>Begut\u00adach\u00adtung vor Ort<\/strong>, die bei laufendem Betrieb der Trans\u00adfor\u00adma\u00adtoren durch\u00adge\u00adf\u00fchrt wird. Bei der visu\u00adellen Inspek\u00adtion \u00fcber\u00adpr\u00fcft ein Experte mittels einer Check\u00adliste den Trans\u00adfor\u00admator nach \u00e4u\u00dfer\u00adli\u00adchen Merk\u00admalen: Gibt es Korrosions\u00aderscheinungen oder Lecks? Sind an den Durch\u00adf\u00fch\u00adrungen oder den Venti\u00adla\u00adtoren sicht\u00adbare Sch\u00e4den zu sehen? Wie alt ist der Motor\u00adan\u00adtrieb? F\u00fcr die Messungen werden ther\u00admo\u00adgra\u00adfi\u00adsche Unter\u00adsu\u00adchungen gemacht und \u00d6lproben entnommen.<img loading=\"lazy\" decoding=\"async\" class=\"mit-rahmen aligncenter wp-image-2511 size-medium\" style=\"margin-top: 10px;margin-bottom: 30px;padding: 5px 50px\" src=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement-Waermesensor-300x260.jpg\" alt width=\"300\" height=\"260\" srcset=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement-Waermesensor-300x260.jpg 300w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement-Waermesensor.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/p>\n<p><span class=\"numbers\">3<\/span> Ergeben sich nach dieser Stufe Hinweise auf gr\u00f6\u00dfere Sch\u00e4den, folgt der dritte Unter\u00adsu\u00adchungs\u00adschritt, bei dem <strong>aufwen\u00addige Messungen<\/strong> wie zum Beispiel eine dyna\u00admi\u00adsche Wider\u00adstands\u00admes\u00adsung oder Teil\u00adent\u00adla\u00addungs\u00admes\u00adsungen durch\u00adge\u00adf\u00fchrt werden. Daf\u00fcr muss der Trans\u00adfor\u00admator aller\u00addings vom Netz.<\/p>\n<p>Die dabei gewon\u00adnenen Daten werden ausge\u00adwertet. Mit dem von der Bergi\u00adschen Univer\u00adsit\u00e4t in Wuppertal und MR entwi\u00adckelten Algo\u00adrithmus erfolgt die Analyse, dann werden die Daten in zwei Indizes \u00fcber\u00adf\u00fchrt: Ein Index gibt Auskunft \u00fcber den Lebens\u00addau\u00ader\u00adver\u00adbrauch, der andere \u00fcber das Ausfall\u00adri\u00adsiko. F\u00fcr die Auswer\u00adtung werden die Ergeb\u00adnisse der beiden Indizes in eine Grafik \u00fcber\u00adf\u00fchrt. So l\u00e4sst sich der Zustand der Transformatoren\u00adflotte einfach visua\u00adli\u00adsieren: Je mehr Trans\u00adfor\u00adma\u00adtoren sich in den Quadranten nahe dem Ursprung befinden, desto besser steht die Flotte da und umge\u00adkehrt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2508 size-full\" src=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement_Index.jpg\" alt width=\"800\" height=\"570\" srcset=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement_Index.jpg 800w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement_Index-300x214.jpg 300w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement_Index-768x547.jpg 768w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Flottenmanagement_Index-540x385.jpg 540w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><\/p>\n<\/div>\n<\/div>\n<p>Das Inter\u00adesse von Babizki war sofort geweckt. Denn er ist auf der Suche nach einer Syste\u00admatik, mit der er den Zustand von Leis\u00adtungs\u00adtrans\u00adfor\u00adma\u00adtoren bestimmen kann. Er wei\u00df, daraus l\u00e4sst sich ein wich\u00adtiger Service f\u00fcr die MR-Kunden entwi\u00adckeln: \u201eWie lang ein Trans\u00adfor\u00admator durch\u00adh\u00e4lt, l\u00e4sst sich nicht pauschal sagen. Es gibt Trans\u00adfor\u00adma\u00adtoren im Indus\u00adtrie\u00adbe\u00adreich, die m\u00fcssen schon nach 15 Jahren ersetzt werden, und dann gibt es solche, die nur mit 30 Prozent Last fahren und schon \u00fcber 50 Jahre im Betrieb sind. Das Alter allein sagt also nicht unbe\u00addingt etwas \u00fcber den Zustand aus\u201c, sagt Babizki. Zdrallek und er sind sich schnell einig: Das ist ein ideales Thema f\u00fcr eine Koope\u00adra\u00adtion.<\/p>\n<blockquote><p>\u201eF\u00fcr uns ist es von stra\u00adte\u00adgi\u00adscher Bedeu\u00adtung, den Zustand unserer Trans\u00adfor\u00adma\u00adtoren genau zu kennen.\u201c<cite>Jan Patrick Linos\u00adsier<\/cite><\/p><\/blockquote>\n<p>\u201eUns fehlte das fundierte Wissen zu den Trans\u00adfor\u00adma\u00adtoren, daf\u00fcr konnten wir unser umfang\u00adrei\u00adches Know-how bez\u00fcg\u00adlich der Konzep\u00adtion von Zustands\u00adbe\u00adwer\u00adtungen einbringen\u201c, erin\u00adnert sich Zdrallek. Der Forscher erhofft sich von dem Projekt, mehr \u00fcber das Alte\u00adrungs\u00adver\u00adhalten von Trans\u00adfor\u00adma\u00adtoren zu erfahren. Denn die Bade\u00adwan\u00adnen\u00adkurve besch\u00e4f\u00adtigt auch ihn. \u201eDie Kurve wird in der Theorie h\u00e4ufig beschrieben und f\u00fcr manche Elemente der Elek\u00adtronik wurde sie auch nach\u00adge\u00adwiesen. Aber ich fragte mich, ob es die Kurve bei Netz\u00adkom\u00adpo\u00adnenten und insbe\u00adson\u00addere Trans\u00adfor\u00adma\u00adtoren \u00fcber\u00adhaupt gibt. Bisher hat sie n\u00e4mlich noch keiner nach\u00adge\u00adwiesen\u201c, so Zdrallek. Die Koope\u00adra\u00adtion zwischen den&nbsp; Part\u00adnern beginnt. In mehreren Treffen und Work\u00adshops entwi\u00adckeln sie gemeinsam eine Bewer\u00adtungs\u00adsys\u00adte\u00admatik.<\/p>\n<h2>LEBENSDAUER UND AUSFALLRISIKO IM BLICK<\/h2>\n<p>Was jedoch noch fehlt, sind Trans\u00adfor\u00adma\u00adtoren, an denen sie ihre Bewer\u00adtungs\u00adsys\u00adte\u00admatik testen k\u00f6nnen. Zdrallek denkt da gleich an die RNG, mit der er bereits zahl\u00adreiche Projekte reali\u00adsiert hat. Dort m\u00fcssen Linos\u00adsier und Funk nicht lange \u00fcber\u00adlegen. \u201eDer Ansatz schien uns sehr viel\u00adver\u00adspre\u00adchend, deshalb willigten wir sofort ein, an einer Pilot\u00adstudie mitzu\u00adwirken\u201c, sagt Linos\u00adsier. Das Beson\u00addere daran: Die Syste\u00admatik (siehe Kasten) betrachtet den Trans\u00adfor\u00admator aus zwei Perspek\u00adtiven. Aus einer lang\u00adfris\u00adtigen, die die Lebens\u00addauer im Blick hat und damit f\u00fcr Inves\u00adti\u00adti\u00adons\u00adent\u00adschei\u00addungen wichtig ist. Und einer kurz\u00adfris\u00adtigen, die auf das Ausfall\u00adri\u00adsiko abzielt und wartungs\u00adre\u00adle\u00advante Entschei\u00addungen betrifft.<\/p>\n<figure id=\"attachment_2631\" aria-describedby=\"caption-attachment-2631\" style=\"width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2631 size-medium\" src=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Zdrallek2-300x200.jpg\" alt width=\"300\" height=\"200\" srcset=\"https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Zdrallek2-300x200.jpg 300w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Zdrallek2-768x512.jpg 768w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Zdrallek2-540x360.jpg 540w, https:\/\/onload.reinhausen.com\/de\/wp-content\/uploads\/sites\/25\/2017\/11\/Zdrallek2.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><figcaption id=\"caption-attachment-2631\" class=\"wp-caption-text\">Markus Zdrallek, Professor an der Bergi\u00adschen Univer\u00adsit\u00e4t in Wuppertal, erhofft sich von der Syste\u00admatik neue Forschungs\u00adim\u00adpulse f\u00fcr das Alte\u00adrungs\u00adver\u00adhalten von Leis\u00adtungs\u00adtrans\u00adfor\u00adma\u00adtoren. (\u00a9 Dirk Moll)<\/figcaption><\/figure>\n<p>Alle Haupt\u00adkom\u00adpo\u00adnenten der Trans\u00adfor\u00adma\u00adtoren werden daf\u00fcr genau unter\u00adsucht: vom Last\u00adstu\u00adfen\u00adschalter \u00fcber den Motor\u00adan\u00adtrieb bis hin zu den Venti\u00adla\u00adtoren f\u00fcr die K\u00fchlung. Insge\u00adsamt ca. 200 Para\u00admeter flie\u00dfen am Ende in die Bewer\u00adtung ein: Daten zur Wartungs\u00adhis\u00adtorie ebenso wie die Ergeb\u00adnisse aus Messungen vor Ort. Das gesam\u00admelte Daten\u00adma\u00adte\u00adrial wird anschlie\u00ad\u00dfend mit einem spezi\u00adellen Algo\u00adrithmus ausge\u00adwertet. \u201eEs gibt zahl\u00adreiche Indi\u00adka\u00adtoren, die auf den Zustand des Trans\u00adfor\u00adma\u00adtors schlie\u00dfen lassen. Zeigt sich zum Beispiel bei der ther\u00admo\u00adgra\u00adfi\u00adschen Messung, dass ein bestimmter Bereich des Trans\u00adfor\u00adma\u00adtors hei\u00df ist, kann man den Fehler eingrenzen. Dann sind detail\u00adlierte Mess\u00adme\u00adthoden erfor\u00adder\u00adlich\u201c, erkl\u00e4rt Zdrallek. Beson\u00adders wichtig f\u00fcr die Beur\u00adtei\u00adlung ist auch die Analyse des \u00d6ls, die MR im Labor ihrer Tochter Messko durch\u00adf\u00fchren kann. Babizki verdeut\u00adlicht: \u201eDas ist ein biss\u00adchen wie beim Blut\u00adbild eines Menschen. Da deutet eine erh\u00f6hte Anzahl wei\u00dfer Blut\u00adk\u00f6r\u00adper\u00adchen auf eine Entz\u00fcn\u00addung hin. Beim Trans\u00adfor\u00adma\u00adto\u00adren\u00f6l ist zum Beispiel ein erh\u00f6hter Acetyl\u00aden\u00adwert ein Hinweis auf einen Licht\u00adbogen \u2013 f\u00fcr den Zustand des Trans\u00adfor\u00adma\u00adtors ist das ein schlechtes Indiz.\u201c<\/p>\n<h2>INSTRUMENT F\u00dcR OBJEKTIVE FLOTTENBEWERTUNG<\/h2>\n<p>F\u00fcr die Pilot\u00adstudie stellte die RNG neun Trans\u00adfor\u00adma\u00adtoren zur Verf\u00fc\u00adgung. Linos\u00adsier erkl\u00e4rt: \u201eWir haben die Auswahl so getroffen, dass sie einen repr\u00e4\u00adsen\u00adta\u00adtiven Quer\u00adschnitt unserer Flotte wider\u00adspie\u00adgelt.\u201c Nach umfang\u00adrei\u00adchen Unter\u00adsu\u00adchungen und der anschlie\u00ad\u00dfenden Auswer\u00adtung standen die Ergeb\u00adnisse fest: Alle Trans\u00adfor\u00adma\u00adtoren befinden sich in einem guten Zustand. Bei manchen kann durch einfache Ma\u00dfnahmen das Ausfall\u00adri\u00adsiko sogar redu\u00adziert und die Nutzungs\u00addauer verl\u00e4n\u00adgert werden. \u201eDas ist der Vorteil unserer Methode: Wir bieten unseren Kunden nicht nur eine Zustands\u00adbe\u00adwer\u00adtung, sondern k\u00f6nnen gleich auch Hand\u00adlungs\u00ademp\u00adfeh\u00adlungen abge\u00adgeben\u201c, betont Babizki.<\/p>\n<p>Die Partner ber\u00fcck\u00adsich\u00adtigten auch Sonder\u00adf\u00e4lle. So deutete bei einem Trans\u00adfor\u00admator ein hoher Acetyl\u00aden\u00adwert auf ein Problem hin. Linos\u00adsier betont: \u201eMR wies uns darauf hin, dass dieser Wert modell\u00adab\u00adh\u00e4ngig vari\u00adieren kann.\u201c Die Grenz\u00adwert\u00ad\u00fcber\u00adschrei\u00adtung im Trans\u00adfor\u00adma\u00adto\u00adren\u00f6l war somit harmlos, eine Erneue\u00adrung w\u00e4re also \u00fcber\u00adfl\u00fcssig gewesen. \u201eWir haben den Algo\u00adrithmus so ausge\u00adlegt, dass der einge\u00adsetzte Stufen\u00adschal\u00adtertyp ber\u00fcck\u00adsich\u00adtigt wird\u201c, erkl\u00e4rt Babizki.<\/p>\n<p>Auch Zdrallek ist mit der neuen Methode zufrieden: \u201eDas ist aus wissen\u00adschaft\u00adli\u00adcher Sicht span\u00adnend. Wenn viele Netz\u00adbe\u00adtreiber damit arbeiten, k\u00f6nnen wir mit dem gewon\u00adnenen Daten\u00adma\u00adte\u00adrial viel\u00adleicht irgend\u00adwann heraus\u00adfinden, ob es die Bade\u00adwan\u00adnen\u00adkurve tats\u00e4ch\u00adlich gibt.\u201c Die RNG jeden\u00adfalls hat beschlossen, einen Gro\u00df\u00adteil ihrer Trans\u00adfor\u00adma\u00adto\u00adren\u00adflotte mit der Methode unter die Lupe zu nehmen. \u201eWir haben jetzt ein Instru\u00adment, mit dem wir den Zustand unserer Flotte objektiv bewerten k\u00f6nnen. F\u00fcr unsere stra\u00adte\u00adgi\u00adschen Entschei\u00addungen ist das enorm wichtig\u201c, betont Linos\u00adsier.<\/p>\n<h5 style=\"margin-bottom: 6px\"><i class=\"fa fa-arrow-right\" style=\"font-size: 80%;color: #222\"><\/i> <a href=\"https:\/\/onload.reinhausen.com\/de\/Flottenmanagement\" target=\"_blank\" rel=\"noopener\">Erfahren Sie noch mehr \u00fcber die Zusam\u00admen\u00adar\u00adbeit im Inter\u00adview mit Jan Patrick Linos\u00adsier und Markus Zdrallek.<\/a><\/h5>\n<hr class=\"yellow\">\n<h2>IHR ANSPRECHPARTNER<\/h2>\n<p><strong>M\u00f6chten auch Sie Ihre Transformatoren\u00adflotte mit der neuen Methode bewerten lassen?<\/strong><\/p>\n<p>Alexei Babi\u00adziki ist f\u00fcr Sie da:<br>\n<a href=\"&#109;&#x61;i&#108;&#x74;&#111;&#x3a;a&#46;&#x62;a&#x62;&#x69;&#122;&#x6b;i&#64;&#x72;e&#x69;&#x6e;&#104;&#x61;u&#115;&#x65;&#110;&#x2e;c&#111;&#x6d;\"><i class=\"wpcmsdev-icon fa fa-envelope-o\"><\/i> &#x61;&#46;&#98;a&#x62;&#x69;&#122;k&#x69;&#x40;&#114;e&#x69;&#x6e;&#104;a&#x75;&#x73;&#101;n&#x2e;&#x63;&#111;m<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie lange halten unsere Trans\u00adfor\u00adma\u00adtoren noch? Diese Frage stellen sich welt\u00adweit immer mehr Netz\u00adbe\u00adtreiber, deren Flotten zuneh\u00admend in die Jahre kommen. Fr\u00fcher entschied oft allein das Alter \u00fcber eine Erneue\u00adrung \u2013 unab\u00adh\u00e4ngig vom tats\u00e4ch\u00adli\u00adchen Zustand. Eine neue Methode \u00e4ndert das.<\/p>\n","protected":false},"author":27,"featured_media":2560,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11-2017"],"acf":[],"_links":{"self":[{"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/posts\/2383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/comments?post=2383"}],"version-history":[{"count":1,"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/posts\/2383\/revisions"}],"predecessor-version":[{"id":8783,"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/posts\/2383\/revisions\/8783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/media\/2560"}],"wp:attachment":[{"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/media?parent=2383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/categories?post=2383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onload.reinhausen.com\/de\/wp-json\/wp\/v2\/tags?post=2383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}